{"id":47349,"date":"2019-08-28T14:01:29","date_gmt":"2019-08-28T20:01:29","guid":{"rendered":"https:\/\/uat-internal.connectforhealthco.com\/wp-content\/uploads\/2019\/08\/Icon-Chat.png"},"modified":"2019-08-28T14:01:29","modified_gmt":"2019-08-28T20:01:29","slug":"icon-chat-2","status":"inherit","type":"attachment","link":"https:\/\/connectforhealthco.com\/es\/icon-chat-2\/","title":{"rendered":"Icon-Chat"},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-47349","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Icon-Chat &#8226; Connect for Health Colorado<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Icon-Chat &#8226; Connect for Health Colorado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png\" \/>\n<meta property=\"og:site_name\" content=\"Connect for Health Colorado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/connectforhealthco\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"109\" \/>\n\t<meta property=\"og:image:height\" content=\"109\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@C4HCO\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/c4-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/28140129\\\/Icon-Chat.png\",\"url\":\"https:\\\/\\\/c4-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/28140129\\\/Icon-Chat.png\",\"name\":\"Icon-Chat &#8226; Connect for Health Colorado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/connectforhealthco.com\\\/#website\"},\"datePublished\":\"2019-08-28T20:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/c4-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/28140129\\\/Icon-Chat.png#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/c4-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/28140129\\\/Icon-Chat.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/c4-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/28140129\\\/Icon-Chat.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/connectforhealthco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Icon-Chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/connectforhealthco.com\\\/#website\",\"url\":\"https:\\\/\\\/connectforhealthco.com\\\/\",\"name\":\"Connect for Health Colorado\",\"description\":\"El Mercado oficial de seguros de salud de Colorado\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/connectforhealthco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Icon-Chat &#8226; Connect for Health Colorado","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Icon-Chat &#8226; Connect for Health Colorado","og_url":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png","og_site_name":"Connect for Health Colorado","article_publisher":"https:\/\/www.facebook.com\/connectforhealthco\/","og_image":[{"width":109,"height":109,"url":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@C4HCO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png","url":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png","name":"Icon-Chat &#8226; Connect for Health Colorado","isPartOf":{"@id":"https:\/\/connectforhealthco.com\/#website"},"datePublished":"2019-08-28T20:01:29+00:00","breadcrumb":{"@id":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/connectforhealthco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Icon-Chat"}]},{"@type":"WebSite","@id":"https:\/\/connectforhealthco.com\/#website","url":"https:\/\/connectforhealthco.com\/","name":"Connect for Health Colorado","description":"El Mercado oficial de seguros de salud de Colorado","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/connectforhealthco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png'><img loading=\"lazy\" decoding=\"async\" width=\"109\" height=\"109\" src=\"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":109,"height":109,"file":"2019\/08\/Icon-Chat.png","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/c4-media.s3.amazonaws.com\/wp-content\/uploads\/2019\/08\/28140129\/Icon-Chat.png","filename":"Icon-Chat.png","filesize":3127,"_links":{"self":[{"href":"https:\/\/connectforhealthco.com\/es\/wp-json\/wp\/v2\/media\/47349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/connectforhealthco.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/connectforhealthco.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/connectforhealthco.com\/es\/wp-json\/wp\/v2\/users\/36"}]}}